{"id":10792,"date":"2022-01-24T12:46:37","date_gmt":"2022-01-24T12:46:37","guid":{"rendered":"https:\/\/ritosa.click.si\/?post_type=product&#038;p=10792"},"modified":"2026-03-30T09:03:06","modified_gmt":"2026-03-30T07:03:06","slug":"tricikel-elektricni-za-odrasle-20-s-kosaro","status":"publish","type":"product","link":"https:\/\/ritosa.click.si\/it\/negozio\/invalidski-pripomocki\/tricikli\/tricikel-elektricni-za-odrasle-20-s-kosaro\/","title":{"rendered":"Triciclo elettrico per adulti 20\u201d con cestino"},"content":{"rendered":"<ul>\n<li data-start=\"323\" data-end=\"609\">Il triciclo \u00e8 dotato di un sedile anatomico per una seduta confortevole, di un ampio cestino posteriore per facilitare il trasporto e di catarifrangenti e luci per una maggiore sicurezza.<\/li>\n<li>Verniciato con vernice anticorrosione, mentre i cerchi e i raggi sono resistenti.<\/li>\n<li>Il modello \u00e8 dotato di differenziale per una maggiore stabilit\u00e0 e una migliore sterzata.<\/li>\n<li>Per facilitarne il trasporto, il triciclo pu\u00f2 essere smontato in due parti.<\/li>\n<li>Batteria: 13 Ah<\/li>\n<li>Capacit\u00e0 di carico (peso massimo del conducente): 130 kg,<\/li>\n<li>Peso: 31 kg<\/li>\n<\/ul>\n<p>Triciclo per bambini e adulti da 140 cm a 185 cm<\/p>","protected":false},"excerpt":{"rendered":"<p data-start=\"87\" data-end=\"164\">Triciclo elettrico da 20\u2033 con differenziale \u2013 per anziani e persone con difficolt\u00e0 di deambulazione.<\/p>\n<p data-start=\"166\" data-end=\"321\">Questo stabile triciclo elettrico \u00e8 adatto a tutte le corporature e garantisce una guida sicura e confortevole anche a chi ha difficolt\u00e0 di equilibrio o di deambulazione. Il telaio in metallo si piega a met\u00e0 per un facile stoccaggio e trasporto. Una scelta perfetta per chi cerca stabilit\u00e0, comfort e praticit\u00e0 nell\u2019uso quotidiano o durante le escursioni.<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":21719,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[496],"product_tag":[],"class_list":["post-10792","product","type-product","status-publish","has-post-thumbnail","product_cat-tricikli","pa_barva-modra","pa_barva-rdeca","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/product\/10792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/media\/21719"}],"wp:attachment":[{"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/media?parent=10792"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/product_brand?post=10792"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/product_cat?post=10792"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ritosa.click.si\/it\/wp-json\/wp\/v2\/product_tag?post=10792"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}